{"id":159,"date":"2021-01-07T14:06:25","date_gmt":"2021-01-07T13:06:25","guid":{"rendered":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/?post_type=paroisse&#038;p=159"},"modified":"2021-01-07T14:06:33","modified_gmt":"2021-01-07T13:06:33","slug":"histoire-de-notre-paroisse","status":"publish","type":"paroisse","link":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/","title":{"rendered":"Histoire de notre paroisse"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"694\" src=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg\" alt=\"\" class=\"wp-image-160\" srcset=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg 523w, https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8-452x600.jpeg 452w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019ABBAYE DE BELCHAMP, SES DEPENDANCES, SES SERFS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jusqu\u2019en 1188, la Cure de Valentigney poss\u00e9da sur place des terres et des serfs ; cette ann\u00e9e-l\u00e0, le cur\u00e9 Villerme r\u00e9signa son \u00e9glise et ses d\u00e9pendances entre les mains de l\u2019archev\u00eaque de Besan\u00e7on qui les conc\u00e9dait lui-m\u00eame \u00e0 l\u2019abbaye de Belchamp (27). (De ce fait, le pr\u00eatre du village allait \u00eatre d\u00e9sormais d\u00e9sign\u00e9 par l\u2019Abb\u00e9). Peu apr\u00e8s, le pape approuvait ces transferts. Dans une bulle confirmative des propri\u00e9t\u00e9s de Belchamp, il citait entre autres l\u2019\u00e9glise de Valentigney, ses hommes, ses champs, prels, for\u00eats, dixmes, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une parti\u00e9 de la gl\u00e8be de Valentigney et quelques manants main mortables d\u00e9pendaient donc de l\u2019abbaye ; si bien que lorsqu\u2019un de ces serfs mourait sans h\u00e9ritier communier, son domaine revenait \u00e0 l\u2019Abb\u00e9 par \u00e9chute (mainmorte personnelle) ; ce fut le cas en 1507 du meix barnard des blans, accens\u00e9 ensuite au Perrin bichenot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019autre part, assez fr\u00e9quemment, le couvent recevait tout ou partie de l\u2019h\u00e9ritage d\u2019un fid\u00e8le qui d\u00e9sirait qu\u2019une messe perp\u00e9tuelle f\u00fbt c\u00e9l\u00e9br\u00e9e le jour anniversaire de sa mort. Ainsi, en 1459, Agnel\u00e2t \u00ab relicte de feu Jehan Chilequey et fille de feu Jehan Vaulderue \u00bb l\u00e9gua ses propri\u00e9t\u00e9s \u00e0 l\u2019\u00e9glise de Belchamp ; elle fondait \u00ab un anniversaire pour le rem\u00e8de et le salut de son \u00e2me et de celles de ses successeurs\u00bb (28).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ses enfants ne go\u00fbt\u00e8rent pas cette pieuse attention ; ils reni\u00e8rent le testament maternel ; l\u2019Abb\u00e9 leur intenta un proc\u00e8s ; il obtint gain de cause \u00e0 condition de leur verser une l\u00e9g\u00e8re indemnit\u00e9 !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec les imp\u00f4ts que nous examinerons plus loin, les \u00abcenses&nbsp;\u00bb procuraient les plus belles ressources \u00e0 l\u2019abbaye ; citons-en deux exemples seulement:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abdu 19 novembre 1529, sur Jean loyon, dud. Valantigney, et Catherine sa femme, la cerise annuelle et perp\u00e9tuelle de cinq sols estev. payable \u00e0 la Saint-Martin d\u2019hyver pour le prix de cinq livres estev. assign\u00e9 sur une vigne dit la grande vigne de Truchaut\u2026m (29). En 1533, \u00absur Claude, Huguenin et Perin fromont, principaux ; Guillaume barbier, Guillaume fromont, Symon bonier de Valantigney et Jehan carray de Dale, plaiges, une cense annuelle et perp\u00e9tuelle de liante sols pour le prix de trante livres\u00bb, assign\u00e9 sur diverses pi\u00e8ces de terre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s la R\u00e9formation, les autorit\u00e9s catholiques et les comtes pro\u00adtestants se disput\u00e8rent la possession de l\u2019abbaye ; celle-ci, ses serfs et ses propriet\u00e9s, pass\u00e8rent finalement \u00e0 la Seigneurie en 1552 ; un Receveur particulier administra pour le Comte les biens et revenus de Belchamp r\u00e9partis dans divers villages, y compris Valentigney.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 31 mars 1584, le prince Fr\u00e9d\u00e9ric affranchissait, contre une forte indemnit\u00e9, environ 300 mainmortables \u00e9tablis sur les anciens domaines de l\u2019abbaye. Or, l\u2019ann\u00e9e pr\u00e9c\u00e9dente, le Receveur et le Procureur charg\u00e9s d\u2019enqu\u00eater sur les disponibilit\u00e9s financi\u00e8res des serfs, avaient constat\u00e9 \u00ab une grande pauvret\u00e9 et piti\u00e9 en la plupart\u2026 chargez de grandes charges seigneuriales, avec peu de moyens et h\u00e9ritages, grandement endebtez, oultre lesd. charges ordinaires&nbsp;\u00bb (30). Dans ces conditions, quelques serfs de Valentigney ne parvinrent pas \u00e0 payer le rachat propos\u00e9 et leurs successeurs rest\u00e8rent longtemps mainmortables, parfois jusqu\u2019en 1793.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est impossible d\u2019en reconstituer la liste continue et compl\u00e8te ; n\u00e9anmoins les archives citent : au 16e&nbsp;si\u00e8cle, les perreney, les mordique ; vers 1627, Henry Merdique et son beau-fr\u00e8re Pierre Chopard ; en 1704, Jean Abram Charpiot; en 1727, Georges Bruot et Caterine Louys sa femme ; Jaque Juillard et Marie Bretey son \u00e9pouse; en 1786, Jaque et Jean Bruot; Georges et Jean Nicolas, fils de feu Isaac Bruot (30).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un terrier des fonds et immeubles mainmortables de l\u2019ancienne abbaye fut reconstitu\u00e9e en 1747, \u00e0 la demande du Prince Charles, par le conseiller Bouthenot qui s\u2019\u00e9tait adjoint l\u2019honorable F.N. Juillard, maire, co-juge de la Pr\u00e9v\u00f4t\u00e9, et J. Fr. Barbier dit Roland ; avant d\u2019assumer cette d\u00e9licate responsabilit\u00e9, les assesseurs avaient \u00abprest\u00e9 serment sur les Saincts Evangiles de Dieu\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une partie des fonds cultiv\u00e9e par des corv\u00e9ables, sujets de la seigneurie, ne relevait donc que de la mainmorte r\u00e9elle ; l\u2019autre \u00e9tait exploit\u00e9e par des manants ou serfs \u00e0 merci (mainmorte personnelle) (31). La surface totale de ces terres atteignait alors, pour nos deux villages, une surface de 508 quartes 15 coupes et demie, soit environ 32 hectares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il serait fastidieux de reproduire en entier ce d\u00e9nombrement qui comprend 74 noms de paysans avec les surfaces respectives de leurs fonds (32). Cependant, notons d\u2019une part les mieux pourvus: F.N. Juillard, avec 36 quartes 6 coupes ; Isaac Renaud Ancien, 24 q. 13 e. ; J. Juillard, de Villers, 19 q. 22 c.; P. Barbiery&nbsp;17 q., etc ; d\u2019autre part, les plus pauvres : Samuel Boillot, 1 quarte 6 coupes ; Isaac Bernard, 1 q. ; P. Gentil, 1 q. ; Daniel Jeanneret, masson, 18 c.; J.-P. Bouton, natif d\u2019Abevillers, 9 c.; etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout tenancier de ces biens mainmortables ne pouvait les vendre, \u00e9changer ou ali\u00e9ner de quelque fa\u00e7on que ce f\u00fbt, sans l\u2019autorisation du Conseil et \u00e0 condition de payer, outre les droits de lods ordi\u00adnaires, un \u00abdroit de consentement\u00bb. Il suffira, \u00e0 titre d\u2019exemples, de retenir ici deux des cas connus :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLe 19 novembre 1791, Elizabeth Barbier, femme de Samuel Renaud, a vendu \u00e0 Pierre et George Juillard, p\u00e8re et fils, un prel sous le Gras, contenant 2 vallemons de condition mainmorta\u00adle envers S.A.S. \u00e0 cause de Belchamp, pour 50 livres en principal, 6 livres de vin et 12 livres d\u2019\u00e9pingles ; a pay\u00e9 14 livres de droit de consentement\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLe 19 may 1770, le sieur L\u00e9opold friderieh Pillard, en qua\u00adlit\u00e9 de commis \u00e0 la Recette des Eglises, a vendu \u00e0 Jean Barbier dit Roland, de Vallantigney, un champ sur le Chachu, d\u2019une quarte, de condition mainmortable envers S.A.S. \u00e0 cause de Belchamp, pour le prix de 25 livres dont les droits de consentement montent \u00e0 2 livres 1 sol 8 deniers\u00bb (32) ; (prix brut de l\u2019are : environ. 4 livres).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme l\u2019Abb\u00e9 autrefois, le Seigneur recevait en \u00e9chute les h\u00e9ri\u00adtages des mainmortables d\u00e9pourvus de successeurs communiers. Ainsi, en 1573, le Receveur mettait aux ench\u00e8res les biens de Jehan perreney, dont les enfants avaient quitt\u00e9 la maison pater\u00adnelle. Vers 1613, on vendait de m\u00eame l\u2019h\u00e9ritage Thomas Mordique. En 1684, Jacquotte BelRoix, veuve de F. Brethey, jadis serf \u00e0 merci \u00e0 Villers-la-Boissiere, disparaissait sans laisser d\u2019enfants ; elle abandonnait au suzerain une maison et quelques terres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Receveur disposait diversement des fonds r\u00e9cup\u00e9r\u00e9s ou dispo\u00adnibles. Il en amodiait quelques-uns pour une dur\u00e9e limit\u00e9e : ainsi Claude Brung lui devait, en 1624, pour ses locations, 30 quartes de froment ; Jacques Regnault le Jeusne, en 1683, 4 livres 10 sols plus 4 quartes de froment et autant d\u2019avoine ; etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il pouvait \u00e9galement les c\u00e9der aux paysans par accensement per\u00adp\u00e9tuel : en 1580, Symon thourot et les freres bruot obtinrent, dans ces conditions, une partie de 1\u2019\u00e9chute perreney ; pour un champ d\u2019environ 4 journaux, ils devaient chaque ann\u00e9e une rente perp\u00e9tuelle de 4 quartes par moiti\u00e9 froment et avoine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019autre part, il constituait ce que l\u2019on appelait au Pa\u00efs des censes ou rentes annuelles, redevances assign\u00e9es \u2013 comme du temps de l\u2019Abb\u00e9 \u2013 sur des biens fonciers confi\u00e9s \u00e0 de bons cultivateurs ; voici trois cas typiques (33) :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDu 27 novembre 1620, sur Jean Juillard le Jeusne, principal, Claude Chambert et Claude Feriot, plaiges, constitution d\u2019une eense annuelle de 21 sols estev. payable \u00e0 la St Martin d\u2019hyver pour le sort principal de 21 livres dites monnoye \u00bb, assign\u00e9 sur une oiche au lieu-dit doz le Mont, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDu 22 octobre 1584, sur Guenot ferriot une cense ou rente annuelle et \u2018ensable de 2 livres 4 sols jusques en fin de r\u00e9achapt pour le prix de 44 livres assign\u00e9 sur une pi\u00e8ce de terre arrible appel\u00e9e dessoulz les noyes devant Villers, etc. s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDu 21 d\u00e9cembre 1562, sur Humbert et Girard juillard, une cense de 4 thinnes de vin rouge, pour le prix de 66 francs, assign\u00e9 sur une vigne de la ceste de trochaud, etc.\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cause de Belchamp, enfin, tous nos villageois payaient un certain nombre d\u2019imp\u00f4ts eccl\u00e9siastiques :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les&nbsp;chai-mages : l\u00e9g\u00e8res redevances per\u00e7ues par les Cures, au Pays. En 1624, Louys Barbier devait 3 gros 3 blancs forts ; Jean Courtot Regnaud, 7 gros ; Mathieu Froment, 7 gros ; etc. (34) ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les&nbsp;anniversaires&nbsp;(messes perp\u00e9tuelles) :&nbsp;en 1601, Cl. et N. Re\u00adgnaud payaient 2 sols pour l\u2019anniversaire de \u00abfut Jehan regnauld= et 8 niquets pour celui de Th\u00e9venin regnauld. Le maintien de ce droit, au Comt\u00e9 de Montb\u00e9liard, ne manque pas de surprendre puisque le catholicisme y \u00e9tait aboli. [Le premier ministre de Valentigney, L\u00e9onard Camuset, fut install\u00e9 le 1er&nbsp;avril 1540. Ce Lorrain, moine augustin d\u00e9froqu\u00e9, avait \u00e9t\u00e9 appel\u00e9 par le c\u00e9l\u00e8bre pr\u00e9dicant de Montb\u00e9liard, Pierre Toussaint son compatriote, ex\u00adchanoine \u00e0 Metz, ancien aum\u00f4nier de Marguerite de Navarre] ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; la d\u00eeme de&nbsp;Belchamp,&nbsp;fournie \u00e9galement aux Cures. A ce litre, Claude Juillard le jeune alias du monnier devait 10 bichots 6 quar\u00adtes par moiti\u00e9 froment et aveine en 1624 ; Claude Juillard le vieulx, 3 quartes de froment en 1615 ; etc. ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; la d\u00eeme de&nbsp;Vallemon :&nbsp;ce&nbsp;canton de champ, appel\u00e9 vallemon ou terrage, s\u2019\u00e9tend \u00e0 proximit\u00e9 de Belchamp, sur le finage de Valentigney ; une d\u00eeme sp\u00e9ciale y \u00e9tait pr\u00e9lev\u00e9e par le Receveur des Eglises dans des conditions particuli\u00e8rement dures et injustes. Contrairement \u00e0 la coutume g\u00e9n\u00e9rale de la onzi\u00e8me gerbe, on d\u00eemait ici \u00e0 la huiti\u00e8me, puis \u00e0 la septi\u00e8me (Nos8, 16, 23, etc). En 1790, Valentigney adressa au Conseil une requ\u00eate \u00abtendante \u00e0 faire d\u00e9clarer que la d\u00eeme du petit vallemon serait prise \u00e0 l\u2019avenir sur le pied de l\u2019onzi\u00e8me gerbe suivant l\u2019usage g\u00e9n\u00e9ral du Pays n; cette dol\u00e9ance soumise au Receveur n\u2019obtint pas de r\u00e9ponse, \u00e0 cette date !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; le&nbsp;coupot&nbsp;de&nbsp;,Bel;champ&nbsp;:&nbsp;redevance eccl\u00e9siastique r\u00e9gl\u00e9e par tous les campagnards du Comt\u00e9 et m\u00eame, \u00e0 Mandeure, par les sujets de l\u2019archev\u00eaque ; elle se justifiait par le fait que Belchamp tenait la nef qui \u00abpassait \u00bb les voyageurs par de l\u00e0 le Doubs. A Valentigney, par exemple en 1650, les possesseurs d\u2019une charrue enti\u00e8re (au moins 4 b\u00eates trahantes) payaient par an une quarte de froment (35) ; ceux qui n\u2019avaient qu\u2019une deuil-charrue, ainsi que les manouvriers, devaient un coupot ; les habitants de Villers, un coupot ; mais on ne r\u00e9clamait qu\u2019un demi-coupot \u00e0 Cl. Thourot \u00e0 cause de sa vieillesse et de sa pauvret\u00e9 notoire ; quant \u00e0 la fille Marguerite Chambert, accabl\u00e9e d\u2019infirmit\u00e9s et \u00e0 M. Bouthenot, pauvre de corps et de biens, elles \u00e9taient reconnues insolvables. A partir de 1759, les Boroiliots fournirent par an \u00abun coupot de froment, outre quatre sols tournois par charrue et un sot,&nbsp;par chaque feu\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Belchamp assurait donc par la voie la plus directe les relations entre, d\u2019une part Mandeure et Valentigney, d\u2019autre part le gros du Comt\u00e9 ; c\u2019\u00e9tait un passage d\u2019importance vitale pour les paysans qui, obligatoirement, se rendaient aux foires et march\u00e9s de la capitale ou \u00e0 des corv\u00e9es seigneuriales. Au Moyen-Age, un pont de bois enjambait le Doubs \u00e0 cet endroit. De l\u00e0, trois chemins bien trac\u00e9s s\u2019engagaient \u00e0 travers la for\u00eat (36). Le premier re\u00adjoignait directement la Perrusse (Prusse) de Voujeaucourt et la route de Mastard (Mathay) (37). Le second aboutissait au gu\u00e9 de Mandeure, \u00e0 la fronti\u00e8re franc-comtoise, \u00e0 proximit\u00e9 de la source du Gras. Le troisi\u00e8me int\u00e9ressait sp\u00e9cia3ement notre localit\u00e9 ; il conduisait \u00e0 Villers en \u00e9vitant les fortes d\u00e9clivit\u00e9s du Mont\u00adRoussot. Si, aujourd\u2019hui, on le prend en sens inverse, on suit d\u2019abord la Novie, qui vient de recouvrer une toute nouvelle im\u00adportance puisqu\u2019elle dessert un quartier moderne; ensuite le Chemin des Praslets qui coupe les p\u00e2turages descendant de la ferme des Buis (38) ; enfin, un sentier dans les bois, en grande partie effac\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1318, \u00e0 la suite d\u2019une sentence arbitrale de 1\u2019escuyer Huguenin de Bavans, les moines avaient r\u00e9par\u00e9 cette voie antique qui montait de Belchamp vers le finage de Valentigney, \u00aben tel mani\u00e8re que chers et cherrautes si pussent acontrer, et que quanz li champs sairai veuz, que li dit prodomes de Velanteigney puissent par lou dit champ \u00e0 cher et charraute sans aucison, per exchoir lou mal chemin de la dicte vie cherraul, se point en y havoit, etc&nbsp;\u00bb&nbsp;(39) ; autrement dit, la charri\u00e8re devait retrouver sa largeur primitive, et les moines l\u2019entretenir de fa\u00e7on que deux voitures puissent l\u2019utiliser de front sans danger ; en retour, la communaut\u00e9 versait 10 livres \u00e0 l\u2019Abb\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au 16e&nbsp;si\u00e8cle, le pont de Belchamp avait disparu ; une barque le rempla\u00e7ait; \u00e0 c\u00f4t\u00e9, un gu\u00e9 permettait le passage des bestiaux, des chars et marchandises. Le Receveur, charg\u00e9 de faire assurer les travers\u00e9es et entretenir la nef, soumissionnait le service de la barque. Le 16 septembre 1648, ce fut Jean Barbier qui l\u2019obtint; il recevait 16 francs 10 gros forts pour une ann\u00e9e \u00e0 condition \u00abde s\u2019asquitter dehument et diligemment et aux jours accoustumez dud passage\u00bb, c\u2019est-\u00e0-dire le samedi et les jours de foire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 8 novembre 1702, le service de la nef \u00e9tait \u00abcri\u00e9 au rabbais et mis en prix par Hon. Jean Bernard, \u00e0 35 francs\u00bb. Apr\u00e8s plu\u00adsieurs offres de baisse, J. Barbier l\u2019emportait pour la somme,de 32 f., \u00abledit J. B. ayant promis de se rendre sur le port dud. Belchamp tous les sambedy et iours de foire depuis le soleil levant iusques au couchant, \u00e0 l\u2019effet de bien passer et repasser tous les particuliers qui ont droit au subiet dud. passage, et d\u2019avoir et observer tous les soings n\u00e9cessaires pour la conservation dud. bateau, \u00e0 peine d\u2019en respondre en son chef\u00bb (40). La nef ne devait servir qu\u2019au transport des personnes. Aussi, en 1626, Jean Fostel fut somm\u00e9 de ne pas utiliser la nouvelle \u00abnef de sappin \u00bb pour passer du bois, des pierres et autres mat\u00e9riaux destin\u00e9s \u00e0 la \u00ab thuyllerie \u00bb d\u2019Arbouans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1710, les \u00e9moluments du passeur s\u2019\u00e9levaient \u00e0 34 francs ; 32 f. en 1725, ce qui repr\u00e9sentait un salaire de moins de 12 sous pour une longue journ\u00e9e d\u2019occupation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au 17e&nbsp;si\u00e8cle, un nouveau gu\u00e9 am\u00e9nag\u00e9 en amont, \u00absous la forge d\u2019Audincourt\u00bb, fut adjoint \u00e0 celui de Belchamp. Dans une requ\u00eate du 5 octobre 1663, les habitants de Valentigney s\u2019\u00e9taient plaints de la d\u00e9t\u00e9rioration des anciens gu\u00e9s (Belchamp et l\u2019Etrier dont nous aurons \u00e0 reparler) par suite des guerres et des crues du Doubs. Ils estimaient que celui de la Forge serait plus s\u00fbr et demandaient au Comte la permission de cr\u00e9er un chemin pour s\u2019y rendre ; ils s\u2019engageaient \u00e0 indemniser les propri\u00e9taires des terres que son trac\u00e9 endommagerait. Apr\u00e8s avis favorable du Con\u00adseil, le Prince accepta cette initiative paysanne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une nouvelle charri\u00e8re reliait donc le sommet de la Novie au gu\u00e9 de la Forge ;[un sentier subsiste encore, peu visible dans les pr\u00e9s ; il s\u2019\u00e9largit \u00e0 travers le bosquet des Combottes (41), se perd dans la prairie pr\u00e8s de la route d\u2019Audincourt \u00e0 Belchamp, voie qui d\u2019ailleurs n\u2019existait pas au 18e&nbsp;si\u00e8cle].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019utilisation de la barque et des gu\u00e9s n\u2019allait pas sans dangers. En p\u00e9riode de crue, les eaux furieuses du Doubs pouvaient engloutir nef et passagers, emporter voitures et bestiaux. Le plus terrible de ces drames survint le 2 novembre 1720 ; le bac ayant chavir\u00e9, onze paysans se noy\u00e8rent, qui laissaient de nombreux orphelins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quoi qu\u2019il en soit, ces lieux de passage ne perdirent de leur im\u00adportance qu\u2019apr\u00e8s la construction des ponts sur le Doubs, \u00e0 Valen\u00adtigney et \u00e0 Audincourt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant \u00e0 la grange de l\u2019ancienne abbaye, les fermiers qui l\u2019exploi\u00adt\u00e8rent furent, les uns des habitants de Valentigney ou des villages voisins, les autres des \u00e9trangers, tel l\u2019anabaptiste suisse Daniel Rich, brebisier \u00e0 Voujeaucourt, qui succ\u00e9da aux Ch\u00e8nelot. En 1726, \u00ab les fr\u00e8res Jean, Jean-Jacques et Jean-Georges Ch\u00e8nelot princi\u00adpaux, Jean Rolland Chainelot et Catherine Sire, leurs p\u00e8re et m\u00e8re, plaiges et cautions\u00bb ont donc obtenu la ferme \u00abpour le terme et tems de neuf ans cons\u00e9cutifs qui prendront leur commencement \u00e0 la St Georges prochaine de la pr\u00e9sente ann\u00e9e 1726 et finiront \u00e0 pareil jour de l\u2019an 1735\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils s\u2019engagent \u00e0 payer \u00abannuellement et \u00e0 chaque jour de Saint Martin d\u2019hyver la quantit\u00e9 de 14 bichots par moiti\u00e9 froment et avoine en bonne et licite graine dans les greniers de la Recette eccl\u00e9siastique dud Montb\u00e9liard et au profit d\u2019icelle, avec 40 livres tournoises pour le canon ordinaire de la pr\u00e9sente ferme ; ils d\u00e9\u00adlivreront aussi 2 bichots par moiti\u00e9 froment et avoine dans les greniers de la Seigneurie et pour le D\u00eeme qui luy appartiennent sur lesd. terres et ladite ferme, etc.\u00bb (42).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que fermiers du Prince, les Chapnelot jouissaient de privil\u00e8ges enviables : exemption de toutes les charges et impo\u00adsitions; droit de p\u00e2turage dans les d\u00e9pendances de la grange et m\u00eame dans la for\u00eat voisine dite de B\u00e9lieu ; droit de faire mettre dix pi\u00e8ces de cochons lorsqu\u2019il y aura paisson enti\u00e8re, la moiti\u00e9 lorsqu\u2019il n\u2019y en aura qu\u2019une demie ; droit d\u2019affuage auxdits bois pour entretenir leurs chariots et charrues ainsi que les cl\u00f4tures n\u00e9cessaires\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les clauses finales du contrat, si longues soient-elles, m\u00e9ritent d\u2019\u00eatre cit\u00e9es \u00e0 l\u2019intention des amateurs d\u2019histoire du Droit ; les voici : a\u2026. sous toutes lesquelles conditions la pr\u00e9sente amodia\u00adtion a \u00e9t\u00e9 faite, promettant lesdits fermiers et leurs pleiges tant conjointement que divis\u00e9ment et l\u2019un pour l\u2019autre, l\u2019un seul pour le tout, de les ex\u00e9cuter ponctuellement, pour seuret\u00e9 de quoy ils obligent tous et singuliers leurs biens meubles et immeubles pr\u00e9\u00adsents et futurs qu\u2019ils ont pour ce fournis, et soumettent \u00e0 toutes cours et juridictions qu\u2019il appartiendra en renon\u00e7ant \u00e0 toutes ex\u00adceptions contraires aux pr\u00e9sentes, m\u00eame au b\u00e9n\u00e9fice de Division, ordre de pr\u00e9vention et discussion de biens ; ladite Catherine Sire ayant m\u00eame renonc\u00e9 sp\u00e9cialement de pr\u00e9dite autorit\u00e9 de son mary au Senatus consult vell\u00e9ien, \u00e0 la Loy Julie, aux authen h\u2019ques siqua taulier et sive ame, et g\u00e9n\u00e9ralement \u00e0 tous droits et loix favorables \u00e0 son sexe \u2026.\u00bb. On ne saurait mieux, apr\u00e8s avoir \u00e9cart\u00e9 tout risque, pr\u00e9ciser l\u2019incapacit\u00e9 d\u2019une \u00e9pouse et m\u00e8re, et souligner les pressions intol\u00e9rables exerc\u00e9es par les autorit\u00e9s mont\u00adb\u00e9liardaises pour supprimer, au 18e&nbsp;si\u00e8cle, les garanties que l\u2019Anti\u00adquit\u00e9 et le Moyen-Age accordaient \u00e0 la femme mari\u00e9e!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1778, la Recette eccl\u00e9siastique, oblig\u00e9e de recourir \u00ab\u00e0 tous les moyens d\u2019augmenter ses revenus \u00e0 peine suffisants pour les char\u00adges qui lui incombent\u00bb, d\u00e9cide de revaloriser le bail. Jean Rich accepte un contrat \u00e0 compter de la St Georges 1780, \u00e0 raison de 2025 francs par an, outre les vins ordinaires; fermage pr\u00e9vu pour 18 ans (43).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personne ne se doutait alors qu\u2019une proche R\u00e9volution emp\u00eacherait cet anabaptiste de tenir enti\u00e8rement ses engagements ; qu\u2019elle abo\u00adlirait le vieux r\u00e9gime qui permettait \u00e0 une abbaye disparue de maintenir sous sa coupe, apr\u00e8s avoir pass\u00e9 la main \u00e0 des princes h\u00e9r\u00e9tiques, une fraction du finage de Valentigney et de ses manants 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(27) Arch. Nat. K 2159<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(28) Arch. Nat. K 2160<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(29) Arch. Nat. K 2157. On a remarqu\u00e9 le taux l\u00e9gal de 5% d\u2019int\u00e9r\u00eats. Il ne variera pas sous l\u2019Ancien r\u00e9gime, au Pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(30) Arch. Nat. K 1726, 2158, 2159, 2163, 2198. Arch. du Doubs E986.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(31) Pour la distinction entre mainmorte r\u00e9elle et mainmorte personnelle, voir G. Bugler, ouvrage cit\u00e9, p. 53 g voir aussi la bibliographie du pr\u00e9sent essai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(32) Arch. du Doubs, E 994.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(33)&nbsp; Voir, entre autres, Ar\u00e7h. Nat. K2157, 2158, 2159, 2163, etc. Arch. du Doubs E 990.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(34)&nbsp; Arch. Nat. K 2195<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(35)&nbsp; Arch. Nat. K 2158.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(36)&nbsp; Aujourd\u2019hui encore en retrouve quelques vestiges de ces anciens chemins ; consulter les Cartes d\u2019Etat-Major, en particulier l\u2019\u00e9dition de 1841. Voir le croquis tir\u00e9 d\u2019une carte de 1750 (illustration n\u00b0 5).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(37)&nbsp; Cette voie s\u2019appelait nagu\u00e8re \u00ab chemin ferr\u00e9\u00bb; est-ce parce qu\u2019il \u00e9tait emprunt\u00e9 par les convois se rendant de la forge d\u2019Audiacourt \u00e0 celle de Bourguignon ? M\u00e9ritait-elle le sens originel de voie gallo-romaine dont la solidit\u00e9 d\u00e9fie les si\u00e8cles ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(38)&nbsp; Ann\u00e9e 1959 : cette g\u00e9n\u00e9reuse gl\u00e8be est boulevers\u00e9e pour faire place \u00e0 un autre quartier : la belle r\u00e9sidence des Buis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(39)&nbsp; Arch. Nat; K 2161 ; Manuscrit Biblioth\u00e8que de Montb\u00e9liard n0 158.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(40)&nbsp; Arch. Nat; K 1986, 2158<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(41)&nbsp; Parenth\u00e8se \u00e9crite en 1959. Depuis, cette voie r\u00e9nov\u00e9e, tr\u00e8s importante, descend du quartier des Buis, rejoint, la route d\u2019Audincourt \u00e0 Belchamp ; ce qui permet d\u2019acc\u00e9der directement au nouveau pont pour Arbouans et Month\u00e9liard ; pont mis en service l\u2019an 1963.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(42)&nbsp; Arch. Nat; K 2086.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(43)&nbsp; Arch Nat. K 2161.<\/p>\n","protected":false},"author":1,"featured_media":160,"parent":156,"menu_order":64,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-159","paroisse","type-paroisse","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide\" \/>\n<meta property=\"og:description\" content=\"L\u2019ABBAYE DE BELCHAMP, SES DEPENDANCES, SES SERFS Jusqu\u2019en 1188, la Cure de Valentigney poss\u00e9da sur place des terres et des serfs ; cette ann\u00e9e-l\u00e0, le cur\u00e9 Villerme r\u00e9signa son \u00e9glise et ses d\u00e9pendances entre les mains de l\u2019archev\u00eaque de Besan\u00e7on qui les conc\u00e9dait lui-m\u00eame \u00e0 l\u2019abbaye de Belchamp (27). (De ce fait, le pr\u00eatre du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Doyenn\u00e9 de Seloncourt Pont-de-Roide\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-07T13:06:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"523\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/\",\"url\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/\",\"name\":\"Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/01\\\/image-8.jpeg\",\"datePublished\":\"2021-01-07T13:06:25+00:00\",\"dateModified\":\"2021-01-07T13:06:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/01\\\/image-8.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/01\\\/image-8.jpeg\",\"width\":523,\"height\":694},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/histoire-de-notre-paroisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre-Dame de Belchamp\",\"item\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un peu d&#8217;histoire\",\"item\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/un-peu-dhistoire\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Histoire de notre paroisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/#website\",\"url\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/\",\"name\":\"Doyenn\u00e9 de Seloncourt Pont-de-Roide\",\"description\":\"Dioc\u00e8se de Belfort - Montb\u00e9liard\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide","og_description":"L\u2019ABBAYE DE BELCHAMP, SES DEPENDANCES, SES SERFS Jusqu\u2019en 1188, la Cure de Valentigney poss\u00e9da sur place des terres et des serfs ; cette ann\u00e9e-l\u00e0, le cur\u00e9 Villerme r\u00e9signa son \u00e9glise et ses d\u00e9pendances entre les mains de l\u2019archev\u00eaque de Besan\u00e7on qui les conc\u00e9dait lui-m\u00eame \u00e0 l\u2019abbaye de Belchamp (27). (De ce fait, le pr\u00eatre du [&hellip;]","og_url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/","og_site_name":"Doyenn\u00e9 de Seloncourt Pont-de-Roide","article_modified_time":"2021-01-07T13:06:33+00:00","og_image":[{"width":523,"height":694,"url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/","url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/","name":"Histoire de notre paroisse - Doyenn\u00e9 de Seloncourt Pont-de-Roide","isPartOf":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/#primaryimage"},"image":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg","datePublished":"2021-01-07T13:06:25+00:00","dateModified":"2021-01-07T13:06:33+00:00","breadcrumb":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/#primaryimage","url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg","contentUrl":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-content\/uploads\/sites\/6\/2021\/01\/image-8.jpeg","width":523,"height":694},{"@type":"BreadcrumbList","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/histoire-de-notre-paroisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/"},{"@type":"ListItem","position":2,"name":"Notre-Dame de Belchamp","item":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/"},{"@type":"ListItem","position":3,"name":"Un peu d&#8217;histoire","item":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/un-peu-dhistoire\/"},{"@type":"ListItem","position":4,"name":"Histoire de notre paroisse"}]},{"@type":"WebSite","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/#website","url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/","name":"Doyenn\u00e9 de Seloncourt Pont-de-Roide","description":"Dioc\u00e8se de Belfort - Montb\u00e9liard","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse"}],"about":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/types\/paroisse"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/159\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/media\/160"}],"wp:attachment":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/media?parent=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}