{"id":180,"date":"2021-01-07T14:20:27","date_gmt":"2021-01-07T13:20:27","guid":{"rendered":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/?post_type=paroisse&#038;p=180"},"modified":"2021-12-02T20:26:43","modified_gmt":"2021-12-02T19:26:43","slug":"etapes-de-la-vie","status":"publish","type":"paroisse","link":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/","title":{"rendered":"\u00c9tapes de la vie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Vous pouvez \u00eatre amen\u00e9s \u00e0 contacter un des services de la paroisse : bapt\u00eame, cat\u00e9chisme, mariage, fun\u00e9railles\u2026 des responsables vous apporteront les informations que vous sollicitez.<\/strong><\/p>\n","protected":false},"author":48,"featured_media":0,"parent":10,"menu_order":47,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-180","paroisse","type-paroisse","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide\" \/>\n<meta property=\"og:description\" content=\"Vous pouvez \u00eatre amen\u00e9s \u00e0 contacter un des services de la paroisse : bapt\u00eame, cat\u00e9chisme, mariage, fun\u00e9railles\u2026 des responsables vous apporteront les informations que vous sollicitez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/\" \/>\n<meta property=\"og:site_name\" content=\"Doyenn\u00e9 de Seloncourt Pont-de-Roide\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T19:26:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/etapes-de-la-vie\\\/\",\"url\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/etapes-de-la-vie\\\/\",\"name\":\"\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/#website\"},\"datePublished\":\"2021-01-07T13:20:27+00:00\",\"dateModified\":\"2021-12-02T19:26:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/etapes-de-la-vie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/etapes-de-la-vie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/etapes-de-la-vie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre-Dame de Belchamp\",\"item\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/paroisses\\\/notre-dame-de-belchamp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9tapes de la vie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/#website\",\"url\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/\",\"name\":\"Doyenn\u00e9 de Seloncourt Pont-de-Roide\",\"description\":\"Dioc\u00e8se de Belfort - Montb\u00e9liard\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diocese-belfort-montbeliard.fr\\\/seloncourt-pont-de-roide\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide","og_description":"Vous pouvez \u00eatre amen\u00e9s \u00e0 contacter un des services de la paroisse : bapt\u00eame, cat\u00e9chisme, mariage, fun\u00e9railles\u2026 des responsables vous apporteront les informations que vous sollicitez.","og_url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/","og_site_name":"Doyenn\u00e9 de Seloncourt Pont-de-Roide","article_modified_time":"2021-12-02T19:26:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/","url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/","name":"\u00c9tapes de la vie - Doyenn\u00e9 de Seloncourt Pont-de-Roide","isPartOf":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/#website"},"datePublished":"2021-01-07T13:20:27+00:00","dateModified":"2021-12-02T19:26:43+00:00","breadcrumb":{"@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/etapes-de-la-vie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/"},{"@type":"ListItem","position":2,"name":"Notre-Dame de Belchamp","item":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/paroisses\/notre-dame-de-belchamp\/"},{"@type":"ListItem","position":3,"name":"\u00c9tapes de la vie"}]},{"@type":"WebSite","@id":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/#website","url":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/","name":"Doyenn\u00e9 de Seloncourt Pont-de-Roide","description":"Dioc\u00e8se de Belfort - Montb\u00e9liard","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse"}],"about":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/types\/paroisse"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/users\/48"}],"version-history":[{"count":0,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/180\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/paroisse\/10"}],"wp:attachment":[{"href":"https:\/\/www.diocese-belfort-montbeliard.fr\/seloncourt-pont-de-roide\/wp-json\/wp\/v2\/media?parent=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}